{"id":44295,"count":2,"description":"","link":"https:\/\/www.erotic-anytime.com\/fanza\/actress\/ishidamana\/","name":"\u77f3\u7530\u307e\u306a","slug":"ishidamana","taxonomy":"actress","meta":[],"_links":{"self":[{"href":"https:\/\/www.erotic-anytime.com\/fanza\/wp-json\/wp\/v2\/actress\/44295"}],"collection":[{"href":"https:\/\/www.erotic-anytime.com\/fanza\/wp-json\/wp\/v2\/actress"}],"about":[{"href":"https:\/\/www.erotic-anytime.com\/fanza\/wp-json\/wp\/v2\/taxonomies\/actress"}],"wp:post_type":[{"href":"https:\/\/www.erotic-anytime.com\/fanza\/wp-json\/wp\/v2\/posts?actress=44295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}